{"id":2114,"date":"2026-05-25T06:52:04","date_gmt":"2026-05-25T06:52:04","guid":{"rendered":"https:\/\/xfdytitanium.com\/?page_id=2114"},"modified":"2026-05-25T06:53:45","modified_gmt":"2026-05-25T06:53:45","slug":"shipping-policy","status":"publish","type":"page","link":"https:\/\/xfdytitanium.com\/es\/shipping-policy\/","title":{"rendered":"Pol\u00edtica de env\u00edo"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2114\" class=\"elementor elementor-2114\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a42aba6 e-flex e-con-boxed e-con e-parent\" data-id=\"a42aba6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d9f7277 e-con-full e-flex e-con e-child\" data-id=\"d9f7277\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17c7a6d elementor-widget elementor-widget-heading\" data-id=\"17c7a6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica de env\u00edo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c224a8 elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8c224a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/xfdytitanium.com\/es\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hogar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-double-angle-pointing-to-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pol\u00edtica de env\u00edo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fcf2508 e-flex e-con-boxed e-con e-parent\" data-id=\"fcf2508\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7e5151 elementor-widget elementor-widget-text-editor\" data-id=\"a7e5151\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>En Shanxi Xinfeng Dingyuan Precision Manufacturing Co., Ltd. para brindar entrega oportuna y eficiente de nuestros productos a nuestros clientes. Enviamos nuestros productos a clientes tanto a nivel nacional como internacional.<\/p><h5>Env\u00edo nacional:<\/h5><p>Enviamos nuestros productos dentro de China continental a trav\u00e9s de varios transportistas, seg\u00fan el producto y la ubicaci\u00f3n del cliente.<\/p><p>Los gastos de env\u00edo nacionales pueden variar seg\u00fan el peso y tama\u00f1o del producto, as\u00ed como el destino del env\u00edo.<\/p><p>El tiempo de entrega estimado para los env\u00edos nacionales suele ser de 3 a 7 d\u00edas h\u00e1biles, seg\u00fan el transportista y el destino del env\u00edo.<\/p><h5>Env\u00edo internacional:<\/h5><p>Enviamos nuestros productos a clientes internacionales a trav\u00e9s de varios transportistas, seg\u00fan el producto y la ubicaci\u00f3n del cliente.<\/p><p>Los gastos de env\u00edo internacional pueden variar seg\u00fan el peso y tama\u00f1o del producto, as\u00ed como el destino del env\u00edo.<\/p><p>El tiempo estimado de entrega de los env\u00edos internacionales var\u00eda seg\u00fan el transportista y el destino del env\u00edo. Los tiempos de entrega pueden verse afectados por la aduana y otros factores fuera de nuestro control.<\/p><p>Tenga en cuenta que no somos responsables de los derechos, impuestos o tarifas aduaneros que pueda imponer el pa\u00eds de destino. El cliente es responsable de dichas tarifas.<\/p><p>Si tiene alguna pregunta o inquietud sobre el env\u00edo, no dude en contactarnos en <a href=\"mailto:taitaikang9@gmail.com\"><u>taitaikang9@gmail.com<\/u><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Shipping Policy Home Shipping Policy At Shanxi Xinfeng Dingyuan Precision Manufacturing Co., Ltd.\u00a0to provide timely and efficient delivery of our products to our customers. We ship our products to customers both domestically and internationally. Domestic Shipping: We ship our products within mainland China via various shipping carriers, depending on the product and the location of [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2114","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/xfdytitanium.com\/es\/wp-json\/wp\/v2\/pages\/2114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xfdytitanium.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xfdytitanium.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xfdytitanium.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xfdytitanium.com\/es\/wp-json\/wp\/v2\/comments?post=2114"}],"version-history":[{"count":7,"href":"https:\/\/xfdytitanium.com\/es\/wp-json\/wp\/v2\/pages\/2114\/revisions"}],"predecessor-version":[{"id":2121,"href":"https:\/\/xfdytitanium.com\/es\/wp-json\/wp\/v2\/pages\/2114\/revisions\/2121"}],"wp:attachment":[{"href":"https:\/\/xfdytitanium.com\/es\/wp-json\/wp\/v2\/media?parent=2114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}